{"id":2533,"date":"2018-02-03T10:16:16","date_gmt":"2018-02-03T10:16:16","guid":{"rendered":"http:\/\/www.ninabuschmann.com?page_id=2533"},"modified":"2025-07-27T17:04:59","modified_gmt":"2025-07-27T17:04:59","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/ninabuschmann.com\/de\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<h1>Datenschutz\u00aderkl\u00e4rung<\/h1>\n<h2>1. Datenschutz auf einen Blick<\/h2>\n<h3>Allgemeine Hinweise<\/h3>\n<p>Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n<h3>Datenerfassung auf dieser Website<\/h3>\n<h4>Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/h4>\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Abschnitt \u201eHinweis zur Verantwortlichen Stelle\u201c in dieser Datenschutzerkl\u00e4rung entnehmen.<\/p>\n<h4>Wie erfassen wir Ihre Daten?<\/h4>\n<p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.\u00a0B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p>\n<p>Andere Daten werden automatisch oder nach Ihrer Einwilligung beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.\u00a0B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie diese Website betreten.<\/p>\n<h4>Wof\u00fcr nutzen wir Ihre Daten?<\/h4>\n<p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/p>\n<h4>Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/h4>\n<p>Sie haben jederzeit das Recht, unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung oder L\u00f6schung dieser Daten zu verlangen. Wenn Sie eine Einwilligung zur Datenverarbeitung erteilt haben, k\u00f6nnen Sie diese Einwilligung jederzeit f\u00fcr die Zukunft widerrufen. Au\u00dferdem haben Sie das Recht, unter bestimmten Umst\u00e4nden die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n<p>Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n<h3>Analyse-Tools und Tools von Dritt\u00adanbietern<\/h3>\n<p>Beim Besuch dieser Website kann Ihr Surf-Verhalten statistisch ausgewertet werden. Das geschieht vor allem mit sogenannten Analyseprogrammen.<\/p>\n<p>Detaillierte Informationen zu diesen Analyseprogrammen finden Sie in der folgenden Datenschutzerkl\u00e4rung.<\/p>\n<h2>2. Hosting<\/h2>\n<p>Wir hosten die Inhalte unserer Website bei folgendem Anbieter:<\/p>\n<h3>Externes Hosting<\/h3>\n<p>Diese Website wird extern gehostet. Die personenbezogenen Daten, die auf dieser Website erfasst werden, werden auf den Servern des Hosters \/ der Hoster gespeichert. Hierbei kann es sich v.\u00a0a. um IP-Adressen, Kontaktanfragen, Meta- und Kommunikationsdaten, Vertragsdaten, Kontaktdaten, Namen, Websitezugriffe und sonstige Daten, die \u00fcber eine Website generiert werden, handeln.<\/p>\n<p>Das externe Hosting erfolgt zum Zwecke der Vertragserf\u00fcllung gegen\u00fcber unseren potenziellen und bestehenden Kunden (Art. 6 Abs. 1 lit. b DSGVO) und im Interesse einer sicheren, schnellen und effizienten Bereitstellung unseres Online-Angebots durch einen professionellen Anbieter (Art. 6 Abs. 1 lit. f DSGVO). Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.\u00a0B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Unser(e) Hoster wird bzw. werden Ihre Daten nur insoweit verarbeiten, wie dies zur Erf\u00fcllung seiner Leistungspflichten erforderlich ist und unsere Weisungen in Bezug auf diese Daten befolgen.<\/p>\n<p>Wir setzen folgende(n) Hoster ein:<\/p>\n<p>AGBu\u0308rgernetz Dillingen e.V.<br \/>\n&#8211; Gescha\u0308ftsstelle &#8211;<br \/>\nGro\u00dfe Allee 24<br \/>\n89407 Dillingen a.d. Donau<\/p>\n<h4>Auftragsverarbeitung<\/h4>\n<p>Wir haben einen Vertrag \u00fcber Auftragsverarbeitung (AVV) zur Nutzung des oben genannten Dienstes geschlossen. Hierbei handelt es sich um einen datenschutzrechtlich vorgeschriebenen Vertrag, der gew\u00e4hrleistet, dass dieser die personenbezogenen Daten unserer Websitebesucher nur nach unseren Weisungen und unter Einhaltung der DSGVO verarbeitet.<\/p>\n<h2>3. Allgemeine Hinweise und Pflicht\u00adinformationen<\/h2>\n<h3>Datenschutz<\/h3>\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend den gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n<p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.\u00a0B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n<h3>Hinweis zur verantwortlichen Stelle<\/h3>\n<p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n<p>Nina Buschmann<br \/>\nZugspitzweg 5<br \/>\nD-82057 Icking<\/p>\n<p>Telefon: <span \n                data-original-string='FrulwA1ApHTMjaSSK77J8A==615Cp2qnzjy+t7Tugg+qBBiIA=='\n                class='apbct-email-encoder'\n                title='Dieser Kontakt wurde von Anti-Spam by CleanTalk verschl\u00fcsselt. Klicken Sie hier, um ihn zu entschl\u00fcsseln. Um die Entschl\u00fcsselung abzuschlie\u00dfen, stellen Sie sicher, dass JavaScript in Ihrem Browser aktiviert ist.'>+4917<span class=\"apbct-blur\">******<\/span>46<\/span><br \/>\nE-Mail: <span \n                data-original-string='4TSPFOfp2qDeIWXmwUIMCw==615Y6W7iU1T4ZDK3i61yI8hXSTvI02DM20G0hpIprYOzYU='\n                class='apbct-email-encoder'\n                title='Dieser Kontakt wurde von Anti-Spam by CleanTalk verschl\u00fcsselt. Klicken Sie hier, um ihn zu entschl\u00fcsseln. Um die Entschl\u00fcsselung abzuschlie\u00dfen, stellen Sie sicher, dass JavaScript in Ihrem Browser aktiviert ist.'>ni<span class=\"apbct-blur\">**<\/span>@<span class=\"apbct-blur\">***********<\/span>nn.com<\/span><\/p>\n<p>Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z.\u00a0B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n<h3>Speicherdauer<\/h3>\n<p>Soweit innerhalb dieser Datenschutzerkl\u00e4rung keine speziellere Speicherdauer genannt wurde, verbleiben Ihre personenbezogenen Daten bei uns, bis der Zweck f\u00fcr die Datenverarbeitung entf\u00e4llt. Wenn Sie ein berechtigtes L\u00f6schersuchen geltend machen oder eine Einwilligung zur Datenverarbeitung widerrufen, werden Ihre Daten gel\u00f6scht, sofern wir keine anderen rechtlich zul\u00e4ssigen Gr\u00fcnde f\u00fcr die Speicherung Ihrer personenbezogenen Daten haben (z.\u00a0B. steuer- oder handelsrechtliche Aufbewahrungsfristen); im letztgenannten Fall erfolgt die L\u00f6schung nach Fortfall dieser Gr\u00fcnde.<\/p>\n<h3>Allgemeine Hinweise zu den Rechtsgrundlagen der Datenverarbeitung auf dieser Website<\/h3>\n<p>Sofern Sie in die Datenverarbeitung eingewilligt haben, verarbeiten wir Ihre personenbezogenen Daten auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO bzw. Art. 9 Abs. 2 lit. a DSGVO, sofern besondere Datenkategorien nach Art. 9 Abs. 1 DSGVO verarbeitet werden. Im Falle einer ausdr\u00fccklichen Einwilligung in die \u00dcbertragung personenbezogener Daten in Drittstaaten erfolgt die Datenverarbeitung au\u00dferdem auf Grundlage von Art. 49 Abs. 1 lit. a DSGVO. Sofern Sie in die Speicherung von Cookies oder in den Zugriff auf Informationen in Ihr Endger\u00e4t (z.\u00a0B. via Device-Fingerprinting) eingewilligt haben, erfolgt die Datenverarbeitung zus\u00e4tzlich auf Grundlage von \u00a7 25 Abs. 1 TDDDG. Die Einwilligung ist jederzeit widerrufbar. Sind Ihre Daten zur Vertragserf\u00fcllung oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich, verarbeiten wir Ihre Daten auf Grundlage des Art. 6 Abs. 1 lit. b DSGVO. Des Weiteren verarbeiten wir Ihre Daten, sofern diese zur Erf\u00fcllung einer rechtlichen Verpflichtung erforderlich sind auf Grundlage von Art. 6 Abs. 1 lit. c DSGVO. Die Datenverarbeitung kann ferner auf Grundlage unseres berechtigten Interesses nach Art. 6 Abs. 1 lit. f DSGVO erfolgen. \u00dcber die jeweils im Einzelfall einschl\u00e4gigen Rechtsgrundlagen wird in den folgenden Abs\u00e4tzen dieser Datenschutzerkl\u00e4rung informiert.<\/p>\n<h3>Hinweis zur Datenweitergabe in datenschutzrechtlich nicht sichere Drittstaaten sowie die Weitergabe an US-Unternehmen, die nicht DPF-zertifiziert sind<\/h3>\n<p>Wir verwenden unter anderem Tools von Unternehmen mit Sitz in datenschutzrechtlich nicht sicheren Drittstaaten sowie US-Tools, deren Anbieter nicht nach dem EU-US-Data Privacy Framework (DPF) zertifiziert sind. Wenn diese Tools aktiv sind, k\u00f6nnen Ihre personenbezogene Daten in diese Staaten \u00fcbertragen und dort verarbeitet werden. Wir weisen darauf hin, dass in datenschutzrechtlich unsicheren Drittstaaten kein mit der EU vergleichbares Datenschutzniveau garantiert werden kann.<\/p>\n<p>Wir weisen darauf hin, dass die USA als sicherer Drittstaat grunds\u00e4tzlich ein mit der EU vergleichbares Datenschutzniveau aufweisen. Eine Daten\u00fcbertragung in die USA ist danach zul\u00e4ssig, wenn der Empf\u00e4nger eine Zertifizierung unter dem \u201eEU-US Data Privacy Framework\u201c (DPF) besitzt oder \u00fcber geeignete zus\u00e4tzliche Garantien verf\u00fcgt. Informationen zu \u00dcbermittlungen an Drittstaaten einschlie\u00dflich der Datenempf\u00e4nger finden Sie in dieser Datenschutzerkl\u00e4rung.<\/p>\n<h3>Empf\u00e4nger von personenbezogenen Daten<\/h3>\n<p>Im Rahmen unserer Gesch\u00e4ftst\u00e4tigkeit arbeiten wir mit verschiedenen externen Stellen zusammen. Dabei ist teilweise auch eine \u00dcbermittlung von personenbezogenen Daten an diese externen Stellen erforderlich. Wir geben personenbezogene Daten nur dann an externe Stellen weiter, wenn dies im Rahmen einer Vertragserf\u00fcllung erforderlich ist, wenn wir gesetzlich hierzu verpflichtet sind (z.\u00a0B. Weitergabe von Daten an Steuerbeh\u00f6rden), wenn wir ein berechtigtes Interesse nach Art. 6 Abs. 1 lit. f DSGVO an der Weitergabe haben oder wenn eine sonstige Rechtsgrundlage die Datenweitergabe erlaubt. Beim Einsatz von Auftragsverarbeitern geben wir personenbezogene Daten unserer Kunden nur auf Grundlage eines g\u00fcltigen Vertrags \u00fcber Auftragsverarbeitung weiter. Im Falle einer gemeinsamen Verarbeitung wird ein Vertrag \u00fcber gemeinsame Verarbeitung geschlossen.<\/p>\n<h3>Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h3>\n<p>Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n<h3>Widerspruchsrecht gegen die Datenerhebung in besonderen F\u00e4llen sowie gegen Direktwerbung (Art. 21 DSGVO)<\/h3>\n<p>WENN DIE DATENVERARBEITUNG AUF GRUNDLAGE VON ART. 6 ABS. 1 LIT. E ODER F DSGVO ERFOLGT, HABEN SIE JEDERZEIT DAS RECHT, AUS GR\u00dcNDEN, DIE SICH AUS IHRER BESONDEREN SITUATION ERGEBEN, GEGEN DIE VERARBEITUNG IHRER PERSONENBEZOGENEN DATEN WIDERSPRUCH EINZULEGEN; DIES GILT AUCH F\u00dcR EIN AUF DIESE BESTIMMUNGEN GEST\u00dcTZTES PROFILING. DIE JEWEILIGE RECHTSGRUNDLAGE, AUF DENEN EINE VERARBEITUNG BERUHT, ENTNEHMEN SIE DIESER DATENSCHUTZERKL\u00c4RUNG. WENN SIE WIDERSPRUCH EINLEGEN, WERDEN WIR IHRE BETROFFENEN PERSONENBEZOGENEN DATEN NICHT MEHR VERARBEITEN, ES SEI DENN, WIR K\u00d6NNEN ZWINGENDE SCHUTZW\u00dcRDIGE GR\u00dcNDE F\u00dcR DIE VERARBEITUNG NACHWEISEN, DIE IHRE INTERESSEN, RECHTE UND FREIHEITEN \u00dcBERWIEGEN ODER DIE VERARBEITUNG DIENT DER GELTENDMACHUNG, AUS\u00dcBUNG ODER VERTEIDIGUNG VON RECHTSANSPR\u00dcCHEN (WIDERSPRUCH NACH ART. 21 ABS. 1 DSGVO).<\/p>\n<p>WERDEN IHRE PERSONENBEZOGENEN DATEN VERARBEITET, UM DIREKTWERBUNG ZU BETREIBEN, SO HABEN SIE DAS RECHT, JEDERZEIT WIDERSPRUCH GEGEN DIE VERARBEITUNG SIE BETREFFENDER PERSONENBEZOGENER DATEN ZUM ZWECKE DERARTIGER WERBUNG EINZULEGEN; DIES GILT AUCH F\u00dcR DAS PROFILING, SOWEIT ES MIT SOLCHER DIREKTWERBUNG IN VERBINDUNG STEHT. WENN SIE WIDERSPRECHEN, WERDEN IHRE PERSONENBEZOGENEN DATEN ANSCHLIESSEND NICHT MEHR ZUM ZWECKE DER DIREKTWERBUNG VERWENDET (WIDERSPRUCH NACH ART. 21 ABS. 2 DSGVO).<\/p>\n<h3>Beschwerde\u00adrecht bei der zust\u00e4ndigen Aufsichts\u00adbeh\u00f6rde<\/h3>\n<p>Im Falle von Verst\u00f6\u00dfen gegen die DSGVO steht den Betroffenen ein Beschwerderecht bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres gew\u00f6hnlichen Aufenthalts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes zu. Das Beschwerderecht besteht unbeschadet anderweitiger verwaltungsrechtlicher oder gerichtlicher Rechtsbehelfe.<\/p>\n<h3>Recht auf Daten\u00ad\u00fcbertrag\u00adbarkeit<\/h3>\n<p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n<h3>Auskunft, Berichtigung und L\u00f6schung<\/h3>\n<p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n<h3>Recht auf Einschr\u00e4nkung der Verarbeitung<\/h3>\n<p>Sie haben das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Hierzu k\u00f6nnen Sie sich jederzeit an uns wenden. Das Recht auf Einschr\u00e4nkung der Verarbeitung besteht in folgenden F\u00e4llen:<\/p>\n<ul>\n<li>Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben\u00f6tigen wir in der Regel Zeit, um dies zu \u00fcberpr\u00fcfen. F\u00fcr die Dauer der Pr\u00fcfung haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<li>Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm\u00e4\u00dfig geschah\/geschieht, k\u00f6nnen Sie statt der L\u00f6schung die Einschr\u00e4nkung der Datenverarbeitung verlangen.<\/li>\n<li>Wenn wir Ihre personenbezogenen Daten nicht mehr ben\u00f6tigen, Sie sie jedoch zur Aus\u00fcbung, Verteidigung oder Geltendmachung von Rechtsanspr\u00fcchen ben\u00f6tigen, haben Sie das Recht, statt der L\u00f6schung die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<li>Wenn Sie einen Widerspruch nach Art. 21 Abs. 1 DSGVO eingelegt haben, muss eine Abw\u00e4gung zwischen Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen \u00fcberwiegen, haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<\/ul>\n<p>Wenn Sie die Verarbeitung Ihrer personenbezogenen Daten eingeschr\u00e4nkt haben, d\u00fcrfen diese Daten \u2013 von ihrer Speicherung abgesehen \u2013 nur mit Ihrer Einwilligung oder zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person oder aus Gr\u00fcnden eines wichtigen \u00f6ffentlichen Interesses der Europ\u00e4ischen Union oder eines Mitgliedstaats verarbeitet werden.<\/p>\n<h3>SSL- bzw. TLS-Verschl\u00fcsselung<\/h3>\n<p>Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL- bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201ehttp:\/\/\u201c auf \u201ehttps:\/\/\u201c wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n<p>Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<h2>4. Datenerfassung auf dieser Website<\/h2>\n<h3>Cookies<\/h3>\n<p>Unsere Internetseiten verwenden so genannte \u201eCookies\u201c. Cookies sind kleine Datenpakete und richten auf Ihrem Endger\u00e4t keinen Schaden an. Sie werden entweder vor\u00fcbergehend f\u00fcr die Dauer einer Sitzung (Session-Cookies) oder dauerhaft (permanente Cookies) auf Ihrem Endger\u00e4t gespeichert. Session-Cookies werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Permanente Cookies bleiben auf Ihrem Endger\u00e4t gespeichert, bis Sie diese selbst l\u00f6schen oder eine automatische L\u00f6schung durch Ihren Webbrowser erfolgt.<\/p>\n<p>Cookies k\u00f6nnen von uns (First-Party-Cookies) oder von Drittunternehmen stammen (sog. Third-Party-Cookies). Third-Party-Cookies erm\u00f6glichen die Einbindung bestimmter Dienstleistungen von Drittunternehmen innerhalb von Webseiten (z.\u00a0B. Cookies zur Abwicklung von Zahlungsdienstleistungen).<\/p>\n<p>Cookies haben verschiedene Funktionen. Zahlreiche Cookies sind technisch notwendig, da bestimmte Webseitenfunktionen ohne diese nicht funktionieren w\u00fcrden (z.\u00a0B. die Warenkorbfunktion oder die Anzeige von Videos). Andere Cookies k\u00f6nnen zur Auswertung des Nutzerverhaltens oder zu Werbezwecken verwendet werden.<\/p>\n<p>Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs, zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (z.\u00a0B. f\u00fcr die Warenkorbfunktion) oder zur Optimierung der Website (z.\u00a0B. Cookies zur Messung des Webpublikums) erforderlich sind (notwendige Cookies), werden auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO gespeichert, sofern keine andere Rechtsgrundlage angegeben wird. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung von notwendigen Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Sofern eine Einwilligung zur Speicherung von Cookies und vergleichbaren Wiedererkennungstechnologien abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage dieser Einwilligung (Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG); die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n<p data-start=\"52\" data-end=\"404\"><strong data-start=\"52\" data-end=\"404\">Zur Verwaltung der eingesetzten Cookies und \u00e4hnlicher Technologien (Tracking-Pixel, Web-Beacons etc.) sowie der diesbez\u00fcglichen Einwilligungen nutzen wir das Consent-Tool &#8222;Real Cookie Banner&#8220;. Einzelheiten zur Funktionsweise von &#8222;Real Cookie Banner&#8220; finden Sie unter <a class=\"\" href=\"https:\/\/devowl.io\/rcb\/data-processing\/\" target=\"_new\" rel=\"noopener\" data-start=\"321\" data-end=\"401\">https:\/\/devowl.io\/rcb\/data-processing\/<\/a>.<\/strong><\/p>\n<p data-start=\"406\" data-end=\"703\">Rechtsgrundlagen f\u00fcr die Verarbeitung personenbezogener Daten in diesem Zusammenhang sind Art. 6 Abs. 1 lit. c DSGVO und Art. 6 Abs. 1 lit. f DSGVO. Unser berechtigtes Interesse besteht in der Verwaltung der eingesetzten Cookies und \u00e4hnlicher Technologien sowie der diesbez\u00fcglichen Einwilligungen.<\/p>\n<p data-start=\"705\" data-end=\"1015\">Die Bereitstellung der personenbezogenen Daten ist weder vertraglich vorgeschrieben noch f\u00fcr einen Vertragsabschluss erforderlich. Sie sind nicht verpflichtet, die personenbezogenen Daten bereitzustellen. Wenn Sie die personenbezogenen Daten nicht bereitstellen, k\u00f6nnen wir Ihre Einwilligungen nicht verwalten.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3>Kontaktformular<\/h3>\n<p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n<p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.\u00a0B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<p>Wir verwenden auf unserer Website das Plugin<strong> \u201eFluent Forms\u201c<\/strong>, um die \u00dcbermittlung von Kontaktanfragen zu erm\u00f6glichen. Die \u00fcbermittelten Daten werden ausschlie\u00dflich zur Bearbeitung Ihres Anliegens verwendet und nicht ohne Ihre Einwilligung weitergegeben. Es erfolgt keine Weitergabe an Drittanbieter.<br data-start=\"679\" data-end=\"682\" \/>Rechtsgrundlage f\u00fcr die Verarbeitung ist Art. 6 Abs. 1 lit. b DSGVO (Vertragserf\u00fcllung bzw. vorvertragliche Ma\u00dfnahmen).<\/p>\n<p>Wir nutzen <strong>Brevo<\/strong> (ehemals Sendinblue) als Dienstleister f\u00fcr die Verarbeitung und den Versand von Formularinhalten und E-Mails. Die Daten werden auf Servern von Brevo in der EU verarbeitet.<br data-start=\"1417\" data-end=\"1420\" \/>Anbieter: Sendinblue GmbH, K\u00f6penicker Stra\u00dfe 126, 10179 Berlin, Deutschland.<br data-start=\"1498\" data-end=\"1501\" \/>Weitere Informationen: <a class=\"cursor-pointer\" href=\"https:\/\/www.brevo.com\/de\/legal\/privacypolicy\/\" target=\"_new\" rel=\"noopener\" data-start=\"1526\" data-end=\"1620\">https:\/\/www.brevo.com\/de\/legal\/privacypolicy\/<\/a><\/p>\n<p>Auf unserer Website ist das Plugin <strong>\u201eIcegram\u201c<\/strong> installiert, das zur Verwaltung von Formularen oder Benachrichtigungen verwendet wird. Wir nutzen Icegram ausschlie\u00dflich lokal ohne Tracking, externe Inhalte oder Pop-up-Funktionen. Eine \u00dcbermittlung personenbezogener Daten an Dritte oder das Setzen von Cookies durch Icegram erfolgt nicht.<\/p>\n<h3>Anfrage per E-Mail oder Telefon<\/h3>\n<p>Wenn Sie uns per E-Mail oder Telefon kontaktieren, wird Ihre Anfrage inklusive aller daraus hervorgehenden personenbezogenen Daten (Name, Anfrage) zum Zwecke der Bearbeitung Ihres Anliegens bei uns gespeichert und verarbeitet. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n<p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Die von Ihnen an uns per Kontaktanfragen \u00fcbersandten Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z.\u00a0B. nach abgeschlossener Bearbeitung Ihres Anliegens). Zwingende gesetzliche Bestimmungen \u2013 insbesondere gesetzliche Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<h2>5. Soziale Medien<\/h2>\n<h3>Social-Media-Elemente mit Shariff<\/h3>\n<p>Auf dieser Website werden Elemente von sozialen Medien verwendet (z.\u00a0B. Facebook, X, Instagram, Pinterest, XING, LinkedIn, Tumblr).<\/p>\n<p>Die Social-Media-Elemente k\u00f6nnen Sie in der Regel anhand der jeweiligen Social-Media-Logos erkennen. Um den Datenschutz auf dieser Website zu gew\u00e4hrleisten, verwenden wir diese Elemente nur zusammen mit der sogenannten \u201eShariff\u201c-L\u00f6sung. Diese Anwendung verhindert, dass die auf dieser Website integrierten Social-Media-Elemente Ihre personenbezogenen Daten schon beim ersten Betreten der Seite an den jeweiligen Anbieter \u00fcbertragen.<\/p>\n<p>Erst wenn Sie das jeweilige Social-Media-Element durch Anklicken der zugeh\u00f6rigen Schaltfl\u00e4che aktivieren, wird eine direkte Verbindung zum Server des Anbieters hergestellt (Einwilligung). Sobald Sie das Social-Media-Element aktivieren, erh\u00e4lt der jeweilige Anbieter die Information, dass Sie mit Ihrer IP-Adresse diese Website besucht haben. Wenn Sie gleichzeitig in Ihrem jeweiligen Social-Media-Account (z.\u00a0B. Facebook) eingeloggt sind, kann der jeweilige Anbieter den Besuch dieser Website Ihrem Benutzerkonto zuordnen.<\/p>\n<p>Das Aktivieren des Plugins stellt eine Einwilligung im Sinne des Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG dar. Diese Einwilligung k\u00f6nnen Sie jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen.<\/p>\n<p>Der Einsatz des Dienstes erfolgt, um die gesetzlich vorgeschriebenen Einwilligungen f\u00fcr den Einsatz bestimmter Technologien einzuholen. Rechtsgrundlage hierf\u00fcr ist Art. 6 Abs. 1 lit. c DSGVO.<\/p>\n<p>&nbsp;<\/p>\n<h3>Unsere Social-Media-Auftritte<\/h3>\n<h4>Diese Datenschutzerkl\u00e4rung gilt f\u00fcr folgende Social-Media-Auftritte<\/h4>\n<ul>\n<li><a href=\"https:\/\/www.xing.com\/profile\/Nina_Buschmann\/web_profiles\" target=\"_blank\" rel=\"noopener\">https:\/\/www.xing.com\/profile\/Nina_Buschmann\/web_profiles<\/a><\/li>\n<li><a href=\"http:\/\/www.linkedin.com\/in\/nina-buschmann\" target=\"_blank\" rel=\"noopener\">www.linkedin.com\/in\/nina-buschmann<\/a><\/li>\n<\/ul>\n<h4>Datenverarbeitung durch soziale Netzwerke<\/h4>\n<p>Wir unterhalten \u00f6ffentlich zug\u00e4ngliche Profile in sozialen Netzwerken. Die im Einzelnen von uns genutzten sozialen Netzwerke finden Sie weiter unten.<\/p>\n<p>Soziale Netzwerke wie Facebook, Twitter etc. k\u00f6nnen Ihr Nutzerverhalten in der Regel umfassend analysieren, wenn Sie deren Website oder eine Website mit integrierten Social-Media-Inhalten (z.\u00a0B. Like-Buttons oder Werbebannern) besuchen. Durch den Besuch unserer Social-Media-Pr\u00e4senzen werden zahlreiche datenschutzrelevante Verarbeitungsvorg\u00e4nge ausgel\u00f6st. Im Einzelnen:<\/p>\n<p>Wenn Sie in Ihrem Social-Media-Account eingeloggt sind und unsere Social-Media-Pr\u00e4senz besuchen, kann der Betreiber des Social-Media-Portals diesen Besuch Ihrem Benutzerkonto zuordnen. Ihre personenbezogenen Daten k\u00f6nnen unter Umst\u00e4nden aber auch dann erfasst werden, wenn Sie nicht eingeloggt sind oder keinen Account beim jeweiligen Social-Media-Portal besitzen. Diese Datenerfassung erfolgt in diesem Fall beispielsweise \u00fcber Cookies, die auf Ihrem Endger\u00e4t gespeichert werden oder durch Erfassung Ihrer IP-Adresse.<\/p>\n<p>Mit Hilfe der so erfassten Daten k\u00f6nnen die Betreiber der Social-Media-Portale Nutzerprofile erstellen, in denen Ihre Pr\u00e4ferenzen und Interessen hinterlegt sind. Auf diese Weise kann Ihnen interessenbezogene Werbung in- und au\u00dferhalb der jeweiligen Social-Media-Pr\u00e4senz angezeigt werden. Sofern Sie \u00fcber einen Account beim jeweiligen sozialen Netzwerk verf\u00fcgen, kann die interessenbezogene Werbung auf allen Ger\u00e4ten angezeigt werden, auf denen Sie eingeloggt sind oder eingeloggt waren.<\/p>\n<p>Bitte beachten Sie au\u00dferdem, dass wir nicht alle Verarbeitungsprozesse auf den Social-Media-Portalen nachvollziehen k\u00f6nnen. Je nach Anbieter k\u00f6nnen daher ggf. weitere Verarbeitungsvorg\u00e4nge von den Betreibern der Social-Media-Portale durchgef\u00fchrt werden. Details hierzu entnehmen Sie den Nutzungsbedingungen und Datenschutzbestimmungen der jeweiligen Social-Media-Portale.<\/p>\n<h4>Rechtsgrundlage<\/h4>\n<p>Unsere Social-Media-Auftritte sollen eine m\u00f6glichst umfassende Pr\u00e4senz im Internet gew\u00e4hrleisten. Hierbei handelt es sich um ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO. Die von den sozialen Netzwerken initiierten Analyseprozesse beruhen ggf. auf abweichenden Rechtsgrundlagen, die von den Betreibern der sozialen Netzwerke anzugeben sind (z.\u00a0B. Einwilligung im Sinne des Art. 6 Abs. 1 lit. a DSGVO).<\/p>\n<h4>Verantwortlicher und Geltendmachung von Rechten<\/h4>\n<p>Wenn Sie einen unserer Social-Media-Auftritte (z. B. LinkedIn) besuchen, sind wir gemeinsam mit dem Betreiber der Social-Media-Plattform f\u00fcr die bei diesem Besuch ausgel\u00f6sten Datenverarbeitungsvorg\u00e4nge verantwortlich. Sie k\u00f6nnen Ihre Rechte (Auskunft, Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung, Daten\u00fcbertragbarkeit und Beschwerde) grunds\u00e4tzlich sowohl gg\u00fc. uns als auch gg\u00fc. dem Betreiber des jeweiligen Social-Media-Portals (z. B. gg\u00fc. LinkedIn) geltend machen.<\/p>\n<p>Bitte beachten Sie, dass wir trotz der gemeinsamen Verantwortlichkeit mit den Social-Media-Portal-Betreibern nicht vollumf\u00e4nglich Einfluss auf die Datenverarbeitungsvorg\u00e4nge der Social-Media-Portale haben. Unsere M\u00f6glichkeiten richten sich ma\u00dfgeblich nach der Unternehmenspolitik des jeweiligen Anbieters.<\/p>\n<h4>Speicherdauer<\/h4>\n<p>Die unmittelbar von uns \u00fcber die Social-Media-Pr\u00e4senz erfassten Daten werden von unseren Systemen gel\u00f6scht, sobald Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt. Gespeicherte Cookies verbleiben auf Ihrem Endger\u00e4t, bis Sie sie l\u00f6schen. Zwingende gesetzliche Bestimmungen \u2013 insb. Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<p>Auf die Speicherdauer Ihrer Daten, die von den Betreibern der sozialen Netzwerke zu eigenen Zwecken gespeichert werden, haben wir keinen Einfluss. F\u00fcr Einzelheiten dazu informieren Sie sich bitte direkt bei den Betreibern der sozialen Netzwerke (z.\u00a0B. in deren Datenschutzerkl\u00e4rung, siehe unten).<\/p>\n<h4>Ihre Rechte<\/h4>\n<p>Sie haben jederzeit das Recht, unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Ihnen steht au\u00dferdem ein Recht auf Widerspruch, auf Daten\u00fcbertragbarkeit und ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu. Ferner k\u00f6nnen Sie die Berichtigung, Sperrung, L\u00f6schung und unter bestimmten Umst\u00e4nden die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten verlangen.<\/p>\n<h4>Soziale Netzwerke im Einzelnen<\/h4>\n<h5>XING<\/h5>\n<p>Wir verf\u00fcgen \u00fcber ein Profil bei XING. Anbieter ist die New Work SE, Dammtorstra\u00dfe 30, 20354 Hamburg, Deutschland. Details zu deren Umgang mit Ihren personenbezogenen Daten entnehmen Sie der Datenschutzerkl\u00e4rung von XING:\u00a0<a href=\"https:\/\/privacy.xing.com\/de\/datenschutzerklaerung\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.xing.com\/de\/datenschutzerklaerung<\/a>.<\/p>\n<h5>LinkedIn<\/h5>\n<p>Wir verf\u00fcgen \u00fcber ein Profil bei LinkedIn. Anbieter ist die LinkedIn Ireland Unlimited Company, Wilton Plaza, Wilton Place, Dublin 2,\u00a0Irland. LinkedIn verwendet Werbecookies.<\/p>\n<p><strong>Wenn Sie LinkedIn-Werbe-Cookies deaktivieren m\u00f6chten, nutzen Sie bitte folgenden Link:\u00a0<\/strong><a href=\"https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.linkedin.com\/psettings\/guest-controls\/retargeting-opt-out<\/a>.<\/p>\n<p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier:\u00a0<a href=\"https:\/\/www.linkedin.com\/legal\/l\/dpa\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.linkedin.com\/legal\/l\/dpa<\/a>\u00a0und\u00a0<a href=\"https:\/\/www.linkedin.com\/legal\/l\/eu-sccs\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.linkedin.com\/legal\/l\/eu-sccs<\/a>.<\/p>\n<p>Details zu deren Umgang mit Ihren personenbezogenen Daten entnehmen Sie der Datenschutzerkl\u00e4rung von LinkedIn:\u00a0<a href=\"https:\/\/www.linkedin.com\/legal\/privacy-policy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.linkedin.com\/legal\/privacy-policy<\/a>.<\/p>\n<h2>6. Analyse-Tools und Werbung<\/h2>\n<h3>WP Statistics<\/h3>\n<p>Diese Website nutzt das Analysetool WP Statistics, um Besucherzugriffe statistisch auszuwerten. Anbieter ist Veronalabs, Tatari 64, 10134, Tallinn, Estland (<a href=\"https:\/\/veronalabs.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/veronalabs.com<\/a>).<\/p>\n<p>Mit WP Statistics k\u00f6nnen wir die Nutzung unserer Website analysieren. WP Statistics erfasst dabei u.\u00a0a. Logdateien (IP-Adresse, Referrer, verwendete Browser, Herkunft des Nutzers, verwendete Suchmaschine) und Aktionen, die die Websitebesucher auf der Seite get\u00e4tigt haben (z.\u00a0B. Klicks und Ansichten).<\/p>\n<p>Die mit WP Statistics erfassten Daten werden ausschlie\u00dflich auf unserem eigenen Server gespeichert.<\/p>\n<p>Die Nutzung dieses Analyse-Tools erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse an der anonymisierten Analyse des Nutzerverhaltens, um sowohl unser Webangebot als auch unsere Werbung zu optimieren. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.\u00a0B. Device-Fingerprinting) im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n<h4>IP-Anonymisierung<\/h4>\n<p>Wir verwenden WP Statistics mit anonymisierter IP. Ihre IP-Adresse wird dabei gek\u00fcrzt, sodass diese Ihnen nicht mehr direkt zugeordnet werden kann.<\/p>\n<h2>7. Plugins und Tools<\/h2>\n<h3 id=\"dsg-thirdparty-youtube\">Youtube<\/h3>\n<p><span class=\"ts-muster-content\">Wir binden die Videos der Plattform \u201cYouTube\u201d des Anbieters Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA, ein. Datenschutzerkl\u00e4rung: <a href=\"https:\/\/www.google.com\/policies\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.google.com\/policies\/privacy\/<\/a>, Opt-Out: <a href=\"https:\/\/adssettings.google.com\/authenticated\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/adssettings.google.com\/authenticated<\/a>.<\/span><\/p>\n<h3>WPML<\/h3>\n<p>WPML verwendet Cookies, um die aktuelle Sprache des Besuchers, die zuletzt besuchte Sprache und die Sprache der angemeldeten Benutzer zu identifizieren.<\/p>\n<p>W\u00e4hrend Sie das Plugin verwenden, gibt WPML \u00fcber Installer Daten bez\u00fcglich der Site frei. Es werden keine Daten des Benutzers selbst weitergegeben.<\/p>\n<h3>CleanTalk<\/h3>\n<p>Diese Website nutzt Anti-Spam Plugins von CleanTalk. Anbieter ist die CleanTalk Inc, 711 S Carson Street, suite 4, Carson City, NV, 89701, USA (nachfolgend \u201eCleanTalk\u201d).<\/p>\n<p>CleanTalk dient dem Schutz unserer Website von Spam-Aktivit\u00e4ten (z.\u00a0B. Verhindern von unerw\u00fcnschter Werbung, unerw\u00fcnschten Nachrichten oder Kommentaren). Zu diesem Zweck erfasst CleanTalk verschiedene personenbezogene Daten wie IP-Adresse, E-Mail-Adresse, Nickname des Nachrichtensenders, Informationen \u00fcber die Technologie von JavaScript im Browser des Senders und die eingegebenen Texte.<\/p>\n<p>Diese Informationen werden an einen Server von CleanTalk in den EU \u00fcbertragen und dort gespeichert.<\/p>\n<p>Aus Sicherheitsgr\u00fcnden und als Schutz vor Spam werden Ihre Daten im CleanTalk Cloud Service verarbeitet und in Logfiles f\u00fcr maximal 31 Tage gespeichert. Nach Ablauf der genannten Frist werden diese Daten vollst\u00e4ndig gel\u00f6scht.<\/p>\n<p>Die Verwendung von CleanTalk erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an einem m\u00f6glichst effektiven Schutz seiner Website Spam-Aktivit\u00e4ten. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TDDDG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers im Sinne des TDDDG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier:<a href=\"https:\/\/cleantalk.org\/publicoffer#privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/cleantalk.org\/publicoffer#privacy<\/a>.<\/p>\n<h4>Auftragsverarbeitung<\/h4>\n<p>Wir haben einen Vertrag \u00fcber Auftragsverarbeitung (AVV) zur Nutzung des oben genannten Dienstes geschlossen. Hierbei handelt es sich um einen datenschutzrechtlich vorgeschriebenen Vertrag, der gew\u00e4hrleistet, dass dieser die personenbezogenen Daten unserer Websitebesucher nur nach unseren Weisungen und unter Einhaltung der DSGVO verarbeitet.<\/p>\n<p>Quelle: <a href=\"https:\/\/www.e-recht24.de\">https:\/\/www.e-recht24.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Datenschutz\u00aderkl\u00e4rung 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf dieser [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2533","page","type-page","status-publish","hentry"],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/ninabuschmann.com\/de\/wp-json\/wp\/v2\/pages\/2533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ninabuschmann.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ninabuschmann.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ninabuschmann.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ninabuschmann.com\/de\/wp-json\/wp\/v2\/comments?post=2533"}],"version-history":[{"count":6,"href":"https:\/\/ninabuschmann.com\/de\/wp-json\/wp\/v2\/pages\/2533\/revisions"}],"predecessor-version":[{"id":40539,"href":"https:\/\/ninabuschmann.com\/de\/wp-json\/wp\/v2\/pages\/2533\/revisions\/40539"}],"wp:attachment":[{"href":"https:\/\/ninabuschmann.com\/de\/wp-json\/wp\/v2\/media?parent=2533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}